{"id":11981,"date":"2019-04-27T12:00:40","date_gmt":"2019-04-27T12:00:40","guid":{"rendered":"http:\/\/huebschlaundry.bitnamiapp.com\/?page_id=11981"},"modified":"2019-04-27T12:00:40","modified_gmt":"2019-04-27T12:00:40","slug":"commercial-laundry","status":"publish","type":"page","link":"https:\/\/huebsch.com\/tw-international\/commercial-laundry\/?lang=en","title":{"rendered":"Commercial Laundry"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":4,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-11981","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.12 (Yoast SEO v26.5) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Commercial Laundry - Huebsch Taiwan<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/huebsch.com\/tw-international\/commercial-laundry\/?lang=en\" \/>\n<meta property=\"og:locale\" content=\"zh_CN\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Commercial Laundry\" \/>\n<meta property=\"og:url\" content=\"https:\/\/huebsch.com\/tw-international\/commercial-laundry\/?lang=en\" \/>\n<meta property=\"og:site_name\" content=\"Huebsch Taiwan\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Huebsch\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/huebsch.com\/tw-international\/commercial-laundry\/?lang=en\",\"url\":\"https:\/\/huebsch.com\/tw-international\/commercial-laundry\/?lang=en\",\"name\":\"Commercial Laundry - Huebsch Taiwan\",\"isPartOf\":{\"@id\":\"https:\/\/huebsch.com\/tw-international\/?lang=zh-hant\/#website\"},\"datePublished\":\"2019-04-27T12:00:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/huebsch.com\/tw-international\/commercial-laundry\/?lang=en#breadcrumb\"},\"inLanguage\":\"zh-Hans\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/huebsch.com\/tw-international\/commercial-laundry\/?lang=en\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/huebsch.com\/tw-international\/commercial-laundry\/?lang=en#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/huebsch.com\/tw-international\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Commercial Laundry\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/huebsch.com\/tw-international\/?lang=zh-hant\/#website\",\"url\":\"https:\/\/huebsch.com\/tw-international\/?lang=zh-hant\/\",\"name\":\"Huebsch Taiwan\",\"description\":\"Your Smart Laundry Partner\",\"publisher\":{\"@id\":\"https:\/\/huebsch.com\/tw-international\/?lang=zh-hant\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/huebsch.com\/tw-international\/?lang=zh-hant\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"zh-Hans\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/huebsch.com\/tw-international\/?lang=zh-hant\/#organization\",\"name\":\"Huebsch\",\"url\":\"https:\/\/huebsch.com\/tw-international\/?lang=zh-hant\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-Hans\",\"@id\":\"https:\/\/huebsch.com\/tw-international\/?lang=zh-hant\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/huebsch.com\/tw-international\/wp-content\/uploads\/sites\/10\/2019\/04\/Huebsch_Color_RGB-e1554987923330.png\",\"contentUrl\":\"https:\/\/huebsch.com\/tw-international\/wp-content\/uploads\/sites\/10\/2019\/04\/Huebsch_Color_RGB-e1554987923330.png\",\"width\":295,\"height\":70,\"caption\":\"Huebsch\"},\"image\":{\"@id\":\"https:\/\/huebsch.com\/tw-international\/?lang=zh-hant\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Huebsch\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Commercial Laundry - Huebsch Taiwan","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/huebsch.com\/tw-international\/commercial-laundry\/?lang=en","og_locale":"zh_CN","og_type":"article","og_title":"Commercial Laundry","og_url":"https:\/\/huebsch.com\/tw-international\/commercial-laundry\/?lang=en","og_site_name":"Huebsch Taiwan","article_publisher":"https:\/\/www.facebook.com\/Huebsch\/","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/huebsch.com\/tw-international\/commercial-laundry\/?lang=en","url":"https:\/\/huebsch.com\/tw-international\/commercial-laundry\/?lang=en","name":"Commercial Laundry - Huebsch Taiwan","isPartOf":{"@id":"https:\/\/huebsch.com\/tw-international\/?lang=zh-hant\/#website"},"datePublished":"2019-04-27T12:00:40+00:00","breadcrumb":{"@id":"https:\/\/huebsch.com\/tw-international\/commercial-laundry\/?lang=en#breadcrumb"},"inLanguage":"zh-Hans","potentialAction":[{"@type":"ReadAction","target":["https:\/\/huebsch.com\/tw-international\/commercial-laundry\/?lang=en"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/huebsch.com\/tw-international\/commercial-laundry\/?lang=en#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/huebsch.com\/tw-international\/"},{"@type":"ListItem","position":2,"name":"Commercial Laundry"}]},{"@type":"WebSite","@id":"https:\/\/huebsch.com\/tw-international\/?lang=zh-hant\/#website","url":"https:\/\/huebsch.com\/tw-international\/?lang=zh-hant\/","name":"Huebsch Taiwan","description":"Your Smart Laundry Partner","publisher":{"@id":"https:\/\/huebsch.com\/tw-international\/?lang=zh-hant\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/huebsch.com\/tw-international\/?lang=zh-hant\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"zh-Hans"},{"@type":"Organization","@id":"https:\/\/huebsch.com\/tw-international\/?lang=zh-hant\/#organization","name":"Huebsch","url":"https:\/\/huebsch.com\/tw-international\/?lang=zh-hant\/","logo":{"@type":"ImageObject","inLanguage":"zh-Hans","@id":"https:\/\/huebsch.com\/tw-international\/?lang=zh-hant\/#\/schema\/logo\/image\/","url":"https:\/\/huebsch.com\/tw-international\/wp-content\/uploads\/sites\/10\/2019\/04\/Huebsch_Color_RGB-e1554987923330.png","contentUrl":"https:\/\/huebsch.com\/tw-international\/wp-content\/uploads\/sites\/10\/2019\/04\/Huebsch_Color_RGB-e1554987923330.png","width":295,"height":70,"caption":"Huebsch"},"image":{"@id":"https:\/\/huebsch.com\/tw-international\/?lang=zh-hant\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Huebsch\/"]}]}},"_links":{"self":[{"href":"https:\/\/huebsch.com\/tw-international\/wp-json\/wp\/v2\/pages\/11981","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/huebsch.com\/tw-international\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/huebsch.com\/tw-international\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/huebsch.com\/tw-international\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/huebsch.com\/tw-international\/wp-json\/wp\/v2\/comments?post=11981"}],"version-history":[{"count":0,"href":"https:\/\/huebsch.com\/tw-international\/wp-json\/wp\/v2\/pages\/11981\/revisions"}],"wp:attachment":[{"href":"https:\/\/huebsch.com\/tw-international\/wp-json\/wp\/v2\/media?parent=11981"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}